{"id":23873,"date":"2025-10-09T21:35:00","date_gmt":"2025-10-10T00:35:00","guid":{"rendered":"https:\/\/oab.estrategia.com\/portal\/?p=23873"},"modified":"2025-10-09T21:51:14","modified_gmt":"2025-10-10T00:51:14","slug":"como-se-acalmar-prova-da-2a-fase-rascunho","status":"publish","type":"post","link":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/","title":{"rendered":"Como se acalmar na prova da 2\u00aa fase: o segredo \u00e9 o rascunho"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Descubra como o rascunho pode ser seu aliado para se acalmar na 2\u00aa fase da prova. Aprenda t\u00e9cnicas simples para controlar a ansiedade.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ol\u00e1, pessoal! Hoje o assunto \u00e9 o <strong>controle emocional na segunda fase da OAB!<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos falar um pouco sobre <strong>como lidar com o nervosismo<\/strong> e como <strong>utilizar algumas ferramentas<\/strong> (como o seu rascunho) podem nos ajudar a ter mais calma durante a prova.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A segunda fase da OAB \u00e9, sem d\u00favida, um dos momentos mais desafiadores na jornada de qualquer futuro advogado. \u00c9 um desafio que exige muito mais do que apenas o dom\u00ednio do Direito. Ela testa sua capacidade de racioc\u00ednio sob press\u00e3o, sua organiza\u00e7\u00e3o, sua clareza na escrita e, acima de tudo, seu equil\u00edbrio emocional.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por isso, vamos pensar juntos em algumas dicas para superar o nervosismo e realizar a prova com mais tranquilidade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-voce-age-no-inicio-da-prova-e-fundamental\" style=\"font-style:normal;font-weight:400\"><span id=\"como-voce-age-no-inicio-da-prova-e-fundamental\"><strong>Como voc\u00ea age no in\u00edcio da prova \u00e9 fundamental<\/strong><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Pense comigo:<\/mark><\/strong> voc\u00ea entra na sala, pega a prova, e o cora\u00e7\u00e3o j\u00e1 est\u00e1 a mil. A adrenalina sobe, a mente come\u00e7a a disparar. Nesse instante, na busca por aliviar a press\u00e3o, a tend\u00eancia natural \u00e9 querer &#8220;despejar&#8221; tudo o que se sabe no papel, o mais r\u00e1pido poss\u00edvel.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pois \u00e9 justamente a\u00ed que mora o perigo. A <strong>pressa, a ansiedade e a falta de clareza podem levar a erros bobos, a respostas incompletas ou mal estruturadas<\/strong>, que comprometem todo o seu esfor\u00e7o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 como tentar correr uma maratona sem aquecer. Voc\u00ea pode at\u00e9 ter energia, mas o risco de uma les\u00e3o \u00e9 enorme. No caso da prova, a &#8220;les\u00e3o&#8221; pode ser uma resposta equivocada, uma pe\u00e7a mal elaborada, ou simplesmente n\u00e3o conseguir expressar o seu racioc\u00ednio de forma clara e objetiva. E o pior, <strong>esses erros iniciais podem gerar uma espiral de autocr\u00edtica e des\u00e2nimo<\/strong>, que afetam toda a sua confian\u00e7a para o restante da prova. \u00c9 um ciclo vicioso que precisamos quebrar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-rascunho-seu-aliado-para-o-controle-do-nervosismo\" style=\"font-style:normal;font-weight:400\"><span id=\"o-rascunho-seu-aliado-para-o-controle-do-nervosismo\"><strong>O Rascunho: Seu aliado para o controle do nervosismo<\/strong><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">E se eu te dissesse que existe uma ferramenta simples, mas muito eficaz, de aliviar o seu nervosismo logo no in\u00edcio da prova? Estou falando do rascunho! Sim, aquele espa\u00e7o em branco pode ser um aliado fundamental para o controle daquela ansiedade que aparece no in\u00edcio da prova.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Imagine o <strong>seu rascunho como um &#8220;primeiro encontro&#8221; com a prova<\/strong>, no qual voc\u00ea n\u00e3o tem compromisso com a perfei\u00e7\u00e3o ou precis\u00e3o. \u00c9 um lugar para descarregar a ang\u00fastia inicial, colocar as ideias em ordem, rabiscar suas primeiras impress\u00f5es, palavras soltas, esquemas, setas.<\/p>\n\n\n\n<div class=\"wp-block-group is-style-cnvs-block-bordered cnvs-block-core-group-1760054953893\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:18px\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\"> \u00c9 o seu espa\u00e7o para &#8220;pensar em voz alta&#8221; no papel.\u00a0<\/mark><\/strong><\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Essa simples a\u00e7\u00e3o de transpor o caos mental para o papel j\u00e1 come\u00e7a a organizar o pensamento e, consequentemente, a acalmar a mente. <\/p>\n\n\n\n<div class=\"wp-block-media-text\" style=\"grid-template-columns:28% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"964\" height=\"960\" src=\"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09212151\/coruja_prof_oab_renata.jpg\" alt=\"rascunho\" class=\"wp-image-24107 size-full\" srcset=\"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09212151\/coruja_prof_oab_renata.jpg 964w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09212151\/coruja_prof_oab_renata-300x300.jpg 300w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09212151\/coruja_prof_oab_renata-150x149.jpg 150w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09212151\/coruja_prof_oab_renata-768x765.jpg 768w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09212151\/coruja_prof_oab_renata-80x80.jpg 80w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09212151\/coruja_prof_oab_renata-380x378.jpg 380w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09212151\/coruja_prof_oab_renata-800x797.jpg 800w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09212151\/coruja_prof_oab_renata-24x24.jpg 24w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09212151\/coruja_prof_oab_renata-48x48.jpg 48w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09212151\/coruja_prof_oab_renata-96x96.jpg 96w\" sizes=\"(max-width: 964px) 100vw, 964px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:#cf2e2e\" class=\"has-inline-color has-white-color\">Isso tem uma base neurocient\u00edfica:<\/mark><\/strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\"> <\/mark>quando estamos ansiosos, nosso c\u00e9rebro entra em modo de &#8220;luta ou fuga&#8221; e o c\u00f3rtex pr\u00e9-frontal, que lida com o racioc\u00ednio l\u00f3gico e a tomada de decis\u00f5es, fica prejudicado. Por sua vez, ao rascunhar, voc\u00ea ativa o seu c\u00f3rtex pr\u00e9-frontal. A a\u00e7\u00e3o de escrever, mesmo que de forma desorganizada inicialmente, for\u00e7a seu c\u00e9rebro a processar informa\u00e7\u00f5es de maneira mais estruturada, diminuindo a resposta de ansiedade.\u00a0<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-style-cnvs-block-bg-light has-background\" style=\"background-color:#fcfa0045\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>O ato de rascunhar torna-se um verdadeiro mapeamento do seu racioc\u00ednio. <\/strong><\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para a <strong>pe\u00e7a pr\u00e1tico-profissional<\/strong>, por exemplo, voc\u00ea pode <strong>esbo\u00e7ar a estrutura, identificar as partes, os pedidos, os fundamentos. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 <strong>nas quest\u00f5es dissertativas<\/strong>, pode come\u00e7ar <strong>listando os pontos-chave<\/strong> que precisam ser abordados, os <strong>artigos de lei relevantes<\/strong>, os <strong>princ\u00edpios jur\u00eddicos<\/strong> aplic\u00e1veis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fazer isso permite que voc\u00ea visualize a totalidade da sua resposta antes de se comprometer com o caderno definitivo. Al\u00e9m disso, ao escrever de forma menos comprometida, voc\u00ea acaba se habituando com o \u201cestar em prova\u201d, diminuindo a sensa\u00e7\u00e3o de estranhamento e ansiedade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-estrategias-praticas-para-um-rascunho-eficaz\" style=\"font-style:normal;font-weight:400\"><span id=\"estrategias-praticas-para-um-rascunho-eficaz\"><strong>Estrat\u00e9gias pr\u00e1ticas para um rascunho eficaz<\/strong><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Entender a import\u00e2ncia do rascunho para o controle da ansiedade n\u00e3o significa sair \u201crascunhando\u201d de qualquer jeito. H\u00e1 cuidados que s\u00e3o essenciais. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, vamos \u00e0s <strong>estrat\u00e9gias pr\u00e1ticas<\/strong> para us\u00e1-lo de forma eficaz na 2\u00aa fase da OAB:<\/p>\n\n\n\n<div class=\"wp-block-group is-style-cnvs-block-bg-light\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">1. Comece pela pe\u00e7a:<\/mark><\/strong> o in\u00edcio da prova, apesar do nervosismo, \u00e9 a hora em que nosso tanque de energia est\u00e1 cheio. Assim, aproveite para fazer a parte mais importante, que vale metade de toda a nota da prova;<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-style-cnvs-block-bg-light\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">2. Leia o enunciado com cautela: <\/mark><\/strong>o reconhecimento da pe\u00e7a acontece aos poucos. \u00c9 muito importante voc\u00ea \u201cn\u00e3o se casar\u201d com a primeira hip\u00f3tese que vier ao ler o enunciado. Recomendo que voc\u00ea leia o enunciado ao menos tr\u00eas vezes: uma primeira leitura de reconhecimento do caso, sem nenhuma anota\u00e7\u00e3o; uma segunda tomando nota dos pontos principais, e uma terceira mais pausada, tomando nota dos detalhes;<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-style-cnvs-block-bg-light\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">3. \u201cDescarregue\u201d e estruture<\/mark>:<\/strong> agora vamos ao rascunho propriamente dito. N\u00e3o tente escrever a resposta completa. Comece colocando as ideias principais, ainda que fora de ordem, como uma forma de aliviar a ansiedade. Em seguida, organize o esqueleto: estrutura da pe\u00e7a, argumentos, artigos de lei. Por fim, se entender necess\u00e1rio (e cab\u00edvel no tempo de prova), teste alguns argumentos, esbo\u00e7ando frases que estar\u00e3o na sua fundamenta\u00e7\u00e3o.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-style-cnvs-block-bg-light\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\"><strong>4. Fa\u00e7a o mesmo com as quest\u00f5es<\/strong>: <\/mark>assim como na pe\u00e7a, fa\u00e7a uma leitura cuidadosa do enunciado (mais de uma vez), descarregue as ideias iniciais no rascunho e, ap\u00f3s, crie a estrutura da sua resposta.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-style-cnvs-block-bg-light\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">5. Gerencie o Tempo<\/mark>:<\/strong> Reserve um tempo espec\u00edfico para o rascunho. Para a pe\u00e7a, 30-40 minutos. Para as quest\u00f5es, talvez 10-15 minutos. N\u00e3o gaste tempo demais, mas tamb\u00e9m n\u00e3o o subestime. Al\u00e9m disso, use s\u00edmbolos e abrevia\u00e7\u00f5es para otimizar a sua escrita. Lembre-se: o rascunho n\u00e3o precisa ser bonito.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text\" style=\"grid-template-columns:18% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/24233133\/coruja_oab_dica_renata.png\" alt=\"\" class=\"wp-image-19609 size-full\" srcset=\"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/24233133\/coruja_oab_dica_renata.png 1024w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/24233133\/coruja_oab_dica_renata-300x300.png 300w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/24233133\/coruja_oab_dica_renata-150x150.png 150w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/24233133\/coruja_oab_dica_renata-768x768.png 768w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/24233133\/coruja_oab_dica_renata-80x80.png 80w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/24233133\/coruja_oab_dica_renata-380x380.png 380w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/24233133\/coruja_oab_dica_renata-800x800.png 800w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/24233133\/coruja_oab_dica_renata-24x24.png 24w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/24233133\/coruja_oab_dica_renata-48x48.png 48w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/24233133\/coruja_oab_dica_renata-96x96.png 96w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><mark style=\"background-color:#fff476\" class=\"has-inline-color has-vivid-red-color\"><strong>DICA EXTRA:<\/strong><\/mark> Teste a utiliza\u00e7\u00e3o do rascunho durante a sua prepara\u00e7\u00e3o final. Isso te deixar\u00e1 mais habituado ao passo-a-passo acima.<\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-outras-dicas-para-o-controle-do-nervosismo\" style=\"font-style:normal;font-weight:400\"><span id=\"outras-dicas-para-o-controle-do-nervosismo\"><strong>Outras dicas para o controle do nervosismo<\/strong><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Embora o rascunho seja um segredo poderoso, ele faz parte de um conjunto maior de estrat\u00e9gias para o controle do nervosismo.<\/p>\n\n\n\n<ul class=\"wp-block-list is-style-cnvs-list-styled-positive\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\"><strong>Aceita\u00e7\u00e3o:<\/strong> <\/mark>\u00c9 normal sentir um certo n\u00edvel de nervosismo. N\u00e3o lute contra ele. Aceite que ele faz parte do processo, mas n\u00e3o deixe que ele te domine. Essa aceita\u00e7\u00e3o diminui a intensidade da emo\u00e7\u00e3o;<\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Respira\u00e7\u00e3o consciente:<\/mark><\/strong> Antes de come\u00e7ar a prova, e sempre que sentir a ansiedade subir, fa\u00e7a algumas respira\u00e7\u00f5es profundas. Inspire lentamente pelo nariz, segure por alguns segundos e expire devagar pela boca. Isso ativa o sistema nervoso parassimp\u00e1tico, respons\u00e1vel pelo relaxamento.<\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Fa\u00e7a pequenas pausas:<\/mark><\/strong> Se sentir que est\u00e1 perdendo o foco ou ficando sobrecarregado, fa\u00e7a uma pausa. Olhe para um ponto fixo na sala, beba um gole de \u00e1gua, v\u00e1 ao banheiro. Pequenos \u201cresets\u201d podem fazer uma grande diferen\u00e7a.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusao\" style=\"font-style:normal;font-weight:400\"><span id=\"conclusao\"><strong>Conclus\u00e3o<\/strong><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A aprova\u00e7\u00e3o na OAB \u00e9 o <strong>resultado de muito estudo, dedica\u00e7\u00e3o e, sim, intelig\u00eancia emocional.<\/strong> O rascunho pode ser o seu grande aliado para transformar a ansiedade em clareza, o caos em organiza\u00e7\u00e3o e o medo em confian\u00e7a. Ele te d\u00e1 permiss\u00e3o para errar antes de acertar, para pensar antes de escrever, para se acalmar antes de agir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o subestime o poder de uma estrat\u00e9gia simples, mas profundamente eficaz. Use o rascunho a seu favor, e voc\u00ea ver\u00e1 que o controle do nervosismo se tornar\u00e1 uma realidade.<\/p>\n\n\n\n<div class=\"wp-block-group is-style-cnvs-block-bordered\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>Refer\u00eancias:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Brand\u00e3o, M. L., Vianna, D. M., Masson, S., &amp; Santos, J.. (2003). <strong>Organiza\u00e7\u00e3o neural de diferentes tipos de medo e suas implica\u00e7\u00f5es na ansiedade<\/strong>. <em>Brazilian Journal of Psychiatry<\/em>, <em>25<\/em>, 36\u201341. https:\/\/doi.org\/10.1590\/S1516-44462003000600009;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esperidi\u00e3o-Antonio, V., Majeski-Colombo, M., Toledo-Monteverde, D., Moraes-Martins, G., Fernandes, J. J., Assis, M. B. de ., &amp; Siqueira-Batista, R.. (2008<strong>). Neurobiologia das emo\u00e7\u00f5es<\/strong>. Archives of Clinical Psychiatry (S\u00e3o Paulo), 35(2), 55\u201365. <a href=\"https:\/\/doi.org\/10.1590\/S0101-60832008000200003\">https:\/\/doi.org\/10.1590\/S0101-60832008000200003<\/a>.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Bons estudos e sucesso na sua prova!<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:20px\"><strong>Quer ser aprovado ou aprovada no Exame OAB?<br><a href=\"https:\/\/oab.estrategia.com\/lp\/assinaturas\/index.html?utm_source=google&amp;utm_medium=cpc&amp;utm_campaign=oab-vd-gsh-marca&amp;gad_source=1&amp;gad_campaignid=14319512082&amp;gbraid=0AAAAADpTrcfj8iGdO_wwldDlbDgCmRXhw&amp;gclid=CjwKCAjw2vTFBhAuEiwAFaScwgoZAkDdGghONc8_MwUkK2x2XCPBLZLgGSRtp9whavGB-JMpS97GXhoCqvUQAvD_BwE\">Temos as melhores op\u00e7\u00f5es AQUI!<\/a><\/strong><\/p>\n\n\n\n<div class=\"wp-block-cover\" style=\"min-height:145px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><img decoding=\"async\" width=\"1024\" height=\"190\" class=\"wp-block-cover__image-background wp-image-2272\" alt=\"\" src=\"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2022\/08\/19111944\/assinatura-oab-banner-exame-de-ordem-oab-assinatura-curso-oab-1024x190.jpg\" style=\"object-position:58% 29%\" data-object-fit=\"cover\" data-object-position=\"58% 29%\" srcset=\"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2022\/08\/19111944\/assinatura-oab-banner-exame-de-ordem-oab-assinatura-curso-oab-1024x190.jpg 1024w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2022\/08\/19111944\/assinatura-oab-banner-exame-de-ordem-oab-assinatura-curso-oab-300x56.jpg 300w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2022\/08\/19111944\/assinatura-oab-banner-exame-de-ordem-oab-assinatura-curso-oab-768x143.jpg 768w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2022\/08\/19111944\/assinatura-oab-banner-exame-de-ordem-oab-assinatura-curso-oab-1536x285.jpg 1536w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2022\/08\/19111944\/assinatura-oab-banner-exame-de-ordem-oab-assinatura-curso-oab-380x71.jpg 380w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2022\/08\/19111944\/assinatura-oab-banner-exame-de-ordem-oab-assinatura-curso-oab-800x149.jpg 800w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2022\/08\/19111944\/assinatura-oab-banner-exame-de-ordem-oab-assinatura-curso-oab-1160x215.jpg 1160w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2022\/08\/19111944\/assinatura-oab-banner-exame-de-ordem-oab-assinatura-curso-oab-150x28.jpg 150w, https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2022\/08\/19111944\/assinatura-oab-banner-exame-de-ordem-oab-assinatura-curso-oab.jpg 1890w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h3 id=\"assinatura-oab\" class=\"titulo-assinatura\">Assinatura OAB<\/h3>\n<p class=\"subtitulo-assinatura\" style=\"display:block!important; line-height: 0;\">Conte\u00fado completo para a 1\u00aa e 2\u00aa fase da OAB.<\/p>\n<a target=\"_blank\" href=\"https:\/\/oab.estrategia.com\/curso\/assinatura-oab\/\" rel=\"noopener\"><button style=\"border-radius: 10px; text-transform: capitalize;\">Acessar<\/button><\/a>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"h-conteudos-exclusivos-e-atualizacoes-em-tempo-real-siga-nossas-redes-e-esteja-sempre-um-passo-a-frente\"><span id=\"conteudos-exclusivos-e-atualizacoes-em-tempo-realsiga-nossas-redes-e-esteja-sempre-um-passo-a-frente\">Conte\u00fados exclusivos e atualiza\u00e7\u00f5es em tempo real?<br>Siga<a href=\"https:\/\/www.instagram.com\/estrategiaoab\/\"> nossas redes<\/a> e esteja sempre um passo \u00e0 frente!<\/span><\/h3>\n\n\n\n<ul class=\"wp-block-social-links has-normal-icon-size has-visible-labels is-horizontal is-content-justification-center is-layout-flex wp-container-core-social-links-is-layout-7d812b4c wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-facebook wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.facebook.com\/oabestrategia?locale=pt_BR\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label\">Facebook<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-instagram wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.instagram.com\/estrategiaoab\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label\">Instagram<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-youtube wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/channel\/UC7rgrKTSF5aOrBGWOw60ovw\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M21.8,8.001c0,0-0.195-1.378-0.795-1.985c-0.76-0.797-1.613-0.801-2.004-0.847c-2.799-0.202-6.997-0.202-6.997-0.202 h-0.009c0,0-4.198,0-6.997,0.202C4.608,5.216,3.756,5.22,2.995,6.016C2.395,6.623,2.2,8.001,2.2,8.001S2,9.62,2,11.238v1.517 c0,1.618,0.2,3.237,0.2,3.237s0.195,1.378,0.795,1.985c0.761,0.797,1.76,0.771,2.205,0.855c1.6,0.153,6.8,0.201,6.8,0.201 s4.203-0.006,7.001-0.209c0.391-0.047,1.243-0.051,2.004-0.847c0.6-0.607,0.795-1.985,0.795-1.985s0.2-1.618,0.2-3.237v-1.517 C22,9.62,21.8,8.001,21.8,8.001z M9.935,14.594l-0.001-5.62l5.404,2.82L9.935,14.594z\"><\/path><\/svg><span class=\"wp-block-social-link-label\">Youtube<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-telegram wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/t.me\/transmissaoEstrategiaOAB\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 128 128\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M28.9700376,63.3244248 C47.6273373,55.1957357 60.0684594,49.8368063 66.2934036,47.2476366 C84.0668845,39.855031 87.7600616,38.5708563 90.1672227,38.528 C90.6966555,38.5191258 91.8804274,38.6503351 92.6472251,39.2725385 C93.294694,39.7979149 93.4728387,40.5076237 93.5580865,41.0057381 C93.6433345,41.5038525 93.7494885,42.63857 93.6651041,43.5252052 C92.7019529,53.6451182 88.5344133,78.2034783 86.4142057,89.5379542 C85.5170662,94.3339958 83.750571,95.9420841 82.0403991,96.0994568 C78.3237996,96.4414641 75.5015827,93.6432685 71.9018743,91.2836143 C66.2690414,87.5912212 63.0868492,85.2926952 57.6192095,81.6896017 C51.3004058,77.5256038 55.3966232,75.2369981 58.9976911,71.4967761 C59.9401076,70.5179421 76.3155302,55.6232293 76.6324771,54.2720454 C76.6721165,54.1030573 76.7089039,53.4731496 76.3346867,53.1405352 C75.9604695,52.8079208 75.4081573,52.921662 75.0095933,53.0121213 C74.444641,53.1403447 65.4461175,59.0880351 48.0140228,70.8551922 C45.4598218,72.6091037 43.1463059,73.4636682 41.0734751,73.4188859 C38.7883453,73.3695169 34.3926725,72.1268388 31.1249416,71.0646282 C27.1169366,69.7617838 23.931454,69.0729605 24.208838,66.8603276 C24.3533167,65.7078514 25.9403832,64.5292172 28.9700376,63.3244248 Z\" \/><\/svg><span class=\"wp-block-social-link-label\">Telegram<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-whatsapp wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/chat.whatsapp.com\/GVIH7MrkoVAGyAxc6MuwWf\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M 12.011719 2 C 6.5057187 2 2.0234844 6.478375 2.0214844 11.984375 C 2.0204844 13.744375 2.4814687 15.462563 3.3554688 16.976562 L 2 22 L 7.2324219 20.763672 C 8.6914219 21.559672 10.333859 21.977516 12.005859 21.978516 L 12.009766 21.978516 C 17.514766 21.978516 21.995047 17.499141 21.998047 11.994141 C 22.000047 9.3251406 20.962172 6.8157344 19.076172 4.9277344 C 17.190172 3.0407344 14.683719 2.001 12.011719 2 z M 12.009766 4 C 14.145766 4.001 16.153109 4.8337969 17.662109 6.3417969 C 19.171109 7.8517969 20.000047 9.8581875 19.998047 11.992188 C 19.996047 16.396187 16.413812 19.978516 12.007812 19.978516 C 10.674812 19.977516 9.3544062 19.642812 8.1914062 19.007812 L 7.5175781 18.640625 L 6.7734375 18.816406 L 4.8046875 19.28125 L 5.2851562 17.496094 L 5.5019531 16.695312 L 5.0878906 15.976562 C 4.3898906 14.768562 4.0204844 13.387375 4.0214844 11.984375 C 4.0234844 7.582375 7.6067656 4 12.009766 4 z M 8.4765625 7.375 C 8.3095625 7.375 8.0395469 7.4375 7.8105469 7.6875 C 7.5815469 7.9365 6.9355469 8.5395781 6.9355469 9.7675781 C 6.9355469 10.995578 7.8300781 12.182609 7.9550781 12.349609 C 8.0790781 12.515609 9.68175 15.115234 12.21875 16.115234 C 14.32675 16.946234 14.754891 16.782234 15.212891 16.740234 C 15.670891 16.699234 16.690438 16.137687 16.898438 15.554688 C 17.106437 14.971687 17.106922 14.470187 17.044922 14.367188 C 16.982922 14.263188 16.816406 14.201172 16.566406 14.076172 C 16.317406 13.951172 15.090328 13.348625 14.861328 13.265625 C 14.632328 13.182625 14.464828 13.140625 14.298828 13.390625 C 14.132828 13.640625 13.655766 14.201187 13.509766 14.367188 C 13.363766 14.534188 13.21875 14.556641 12.96875 14.431641 C 12.71875 14.305641 11.914938 14.041406 10.960938 13.191406 C 10.218937 12.530406 9.7182656 11.714844 9.5722656 11.464844 C 9.4272656 11.215844 9.5585938 11.079078 9.6835938 10.955078 C 9.7955938 10.843078 9.9316406 10.663578 10.056641 10.517578 C 10.180641 10.371578 10.223641 10.267562 10.306641 10.101562 C 10.389641 9.9355625 10.347156 9.7890625 10.285156 9.6640625 C 10.223156 9.5390625 9.737625 8.3065 9.515625 7.8125 C 9.328625 7.3975 9.131125 7.3878594 8.953125 7.3808594 C 8.808125 7.3748594 8.6425625 7.375 8.4765625 7.375 z\"><\/path><\/svg><span class=\"wp-block-social-link-label\">WhatsApp<\/span><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"Descubra como o rascunho pode ser seu aliado para se acalmar na 2\u00aa fase da prova. Aprenda t\u00e9cnicas&hellip;\n","protected":false},"author":121,"featured_media":24116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[31,1],"tags":[92,453,452,430,131,52,58,301,100],"class_list":["post-23873","post","type-post","status-publish","format-standard","has-post-thumbnail","category-2a-fase-oab","category-carreira","tag-2a-fase-oab","tag-ansiedade","tag-controle-emocional","tag-dica-de-prova","tag-dicas-de-estudos","tag-estrategia-oab","tag-exame-da-ordem","tag-inteligencia-emocional","tag-prova-oab"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rascunho: por que ele \u00e9 o seu maior aliado na 2\u00aa fase da OAB?<\/title>\n<meta name=\"description\" content=\"Descubra como o rascunho pode ser seu aliado para se acalmar na 2\u00aa fase da prova. Aprenda t\u00e9cnicas simples para controlar a ansiedade.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como se acalmar na prova da 2\u00aa fase: o segredo \u00e9 o rascunho\" \/>\n<meta property=\"og:description\" content=\"Descubra como o rascunho pode ser seu aliado para se acalmar na 2\u00aa fase da prova. Aprenda t\u00e9cnicas simples para controlar a ansiedade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - OAB - Estrat\u00e9gia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/estrategiaoab\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-10T00:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-10T00:51:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oab.estrategia.com\/portal\/portal\/wp-content\/uploads\/2025\/10\/09213216\/como-se-acalmar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"962\" \/>\n\t<meta property=\"og:image:height\" content=\"631\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathan Barros Osipe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@estrategiaoab\" \/>\n<meta name=\"twitter:site\" content=\"@estrategiaoab\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathan Barros Osipe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/como-se-acalmar-prova-da-2a-fase-rascunho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/como-se-acalmar-prova-da-2a-fase-rascunho\\\/\"},\"author\":{\"name\":\"Nathan Barros Osipe\",\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/#\\\/schema\\\/person\\\/fccf66e08e0be1cdca444eeb1ef511d0\"},\"headline\":\"Como se acalmar na prova da 2\u00aa fase: o segredo \u00e9 o rascunho\",\"datePublished\":\"2025-10-10T00:35:00+00:00\",\"dateModified\":\"2025-10-10T00:51:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/como-se-acalmar-prova-da-2a-fase-rascunho\\\/\"},\"wordCount\":1379,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/como-se-acalmar-prova-da-2a-fase-rascunho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/09213216\\\/como-se-acalmar.jpg\",\"keywords\":[\"2\u00aa fase OAB\",\"ansiedade\",\"controle emocional\",\"dica de prova\",\"dicas de estudos\",\"Estrat\u00e9gia OAB\",\"Exame da Ordem\",\"Intelig\u00eancia Emocional\",\"prova OAB\"],\"articleSection\":[\"2\u00aa Fase OAB\",\"Carreira\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/como-se-acalmar-prova-da-2a-fase-rascunho\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/como-se-acalmar-prova-da-2a-fase-rascunho\\\/\",\"url\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/como-se-acalmar-prova-da-2a-fase-rascunho\\\/\",\"name\":\"Rascunho: por que ele \u00e9 o seu maior aliado na 2\u00aa fase da OAB?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/como-se-acalmar-prova-da-2a-fase-rascunho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/como-se-acalmar-prova-da-2a-fase-rascunho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/09213216\\\/como-se-acalmar.jpg\",\"datePublished\":\"2025-10-10T00:35:00+00:00\",\"dateModified\":\"2025-10-10T00:51:14+00:00\",\"description\":\"Descubra como o rascunho pode ser seu aliado para se acalmar na 2\u00aa fase da prova. Aprenda t\u00e9cnicas simples para controlar a ansiedade.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/como-se-acalmar-prova-da-2a-fase-rascunho\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/como-se-acalmar-prova-da-2a-fase-rascunho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/como-se-acalmar-prova-da-2a-fase-rascunho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/09213216\\\/como-se-acalmar.jpg\",\"contentUrl\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/09213216\\\/como-se-acalmar.jpg\",\"width\":962,\"height\":631},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/como-se-acalmar-prova-da-2a-fase-rascunho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como se acalmar na prova da 2\u00aa fase: o segredo \u00e9 o rascunho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/\",\"name\":\"Blog - OAB - Estrat\u00e9gia\",\"description\":\"Blog OAB - Estrat\u00e9gia Concursos\",\"publisher\":{\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/06103601\\\/oab-icone-2.png\",\"contentUrl\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/06103601\\\/oab-icone-2.png\",\"width\":900,\"height\":900,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/estrategiaoab\\\/\",\"https:\\\/\\\/x.com\\\/estrategiaoab\",\"https:\\\/\\\/www.instagram.com\\\/estrategiaoab\\\/\",\"https:\\\/\\\/www.youtube.com\\\/EstrategiaOAB\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/#\\\/schema\\\/person\\\/fccf66e08e0be1cdca444eeb1ef511d0\",\"name\":\"Nathan Barros Osipe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/20100255\\\/professor-nathanosipe-estrategia-oab-96x96.jpg\",\"url\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/20100255\\\/professor-nathanosipe-estrategia-oab-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/20100255\\\/professor-nathanosipe-estrategia-oab-96x96.jpg\",\"caption\":\"Nathan Barros Osipe\"},\"description\":\"Psicanalista. Mestre em Direito. Servidor p\u00fablico (TRF4). Professor da UNIFIO.\",\"url\":\"https:\\\/\\\/oab.estrategia.com\\\/portal\\\/author\\\/nathan-barros-osipe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rascunho: por que ele \u00e9 o seu maior aliado na 2\u00aa fase da OAB?","description":"Descubra como o rascunho pode ser seu aliado para se acalmar na 2\u00aa fase da prova. Aprenda t\u00e9cnicas simples para controlar a ansiedade.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/","og_locale":"pt_BR","og_type":"article","og_title":"Como se acalmar na prova da 2\u00aa fase: o segredo \u00e9 o rascunho","og_description":"Descubra como o rascunho pode ser seu aliado para se acalmar na 2\u00aa fase da prova. Aprenda t\u00e9cnicas simples para controlar a ansiedade.","og_url":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/","og_site_name":"Blog - OAB - Estrat\u00e9gia","article_publisher":"https:\/\/www.facebook.com\/estrategiaoab\/","article_published_time":"2025-10-10T00:35:00+00:00","article_modified_time":"2025-10-10T00:51:14+00:00","og_image":[{"width":962,"height":631,"url":"https:\/\/oab.estrategia.com\/portal\/portal\/wp-content\/uploads\/2025\/10\/09213216\/como-se-acalmar.jpg","type":"image\/jpeg"}],"author":"Nathan Barros Osipe","twitter_card":"summary_large_image","twitter_creator":"@estrategiaoab","twitter_site":"@estrategiaoab","twitter_misc":{"Escrito por":"Nathan Barros Osipe","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/#article","isPartOf":{"@id":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/"},"author":{"name":"Nathan Barros Osipe","@id":"https:\/\/oab.estrategia.com\/portal\/#\/schema\/person\/fccf66e08e0be1cdca444eeb1ef511d0"},"headline":"Como se acalmar na prova da 2\u00aa fase: o segredo \u00e9 o rascunho","datePublished":"2025-10-10T00:35:00+00:00","dateModified":"2025-10-10T00:51:14+00:00","mainEntityOfPage":{"@id":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/"},"wordCount":1379,"commentCount":0,"publisher":{"@id":"https:\/\/oab.estrategia.com\/portal\/#organization"},"image":{"@id":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/#primaryimage"},"thumbnailUrl":"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09213216\/como-se-acalmar.jpg","keywords":["2\u00aa fase OAB","ansiedade","controle emocional","dica de prova","dicas de estudos","Estrat\u00e9gia OAB","Exame da Ordem","Intelig\u00eancia Emocional","prova OAB"],"articleSection":["2\u00aa Fase OAB","Carreira"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/","url":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/","name":"Rascunho: por que ele \u00e9 o seu maior aliado na 2\u00aa fase da OAB?","isPartOf":{"@id":"https:\/\/oab.estrategia.com\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/#primaryimage"},"image":{"@id":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/#primaryimage"},"thumbnailUrl":"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09213216\/como-se-acalmar.jpg","datePublished":"2025-10-10T00:35:00+00:00","dateModified":"2025-10-10T00:51:14+00:00","description":"Descubra como o rascunho pode ser seu aliado para se acalmar na 2\u00aa fase da prova. Aprenda t\u00e9cnicas simples para controlar a ansiedade.","breadcrumb":{"@id":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/#primaryimage","url":"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09213216\/como-se-acalmar.jpg","contentUrl":"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09213216\/como-se-acalmar.jpg","width":962,"height":631},{"@type":"BreadcrumbList","@id":"https:\/\/oab.estrategia.com\/portal\/como-se-acalmar-prova-da-2a-fase-rascunho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/oab.estrategia.com\/portal\/"},{"@type":"ListItem","position":2,"name":"Como se acalmar na prova da 2\u00aa fase: o segredo \u00e9 o rascunho"}]},{"@type":"WebSite","@id":"https:\/\/oab.estrategia.com\/portal\/#website","url":"https:\/\/oab.estrategia.com\/portal\/","name":"Blog - OAB - Estrat\u00e9gia","description":"Blog OAB - Estrat\u00e9gia Concursos","publisher":{"@id":"https:\/\/oab.estrategia.com\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oab.estrategia.com\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/oab.estrategia.com\/portal\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/oab.estrategia.com\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oab.estrategia.com\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2022\/04\/06103601\/oab-icone-2.png","contentUrl":"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2022\/04\/06103601\/oab-icone-2.png","width":900,"height":900,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/oab.estrategia.com\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/estrategiaoab\/","https:\/\/x.com\/estrategiaoab","https:\/\/www.instagram.com\/estrategiaoab\/","https:\/\/www.youtube.com\/EstrategiaOAB"]},{"@type":"Person","@id":"https:\/\/oab.estrategia.com\/portal\/#\/schema\/person\/fccf66e08e0be1cdca444eeb1ef511d0","name":"Nathan Barros Osipe","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/20100255\/professor-nathanosipe-estrategia-oab-96x96.jpg","url":"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/20100255\/professor-nathanosipe-estrategia-oab-96x96.jpg","contentUrl":"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/06\/20100255\/professor-nathanosipe-estrategia-oab-96x96.jpg","caption":"Nathan Barros Osipe"},"description":"Psicanalista. Mestre em Direito. Servidor p\u00fablico (TRF4). Professor da UNIFIO.","url":"https:\/\/oab.estrategia.com\/portal\/author\/nathan-barros-osipe\/"}]}},"jetpack_featured_media_url":"https:\/\/oab.estrategia.com\/portal\/wp-content\/uploads\/2025\/10\/09213216\/como-se-acalmar.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/oab.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/23873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oab.estrategia.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oab.estrategia.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oab.estrategia.com\/portal\/wp-json\/wp\/v2\/users\/121"}],"replies":[{"embeddable":true,"href":"https:\/\/oab.estrategia.com\/portal\/wp-json\/wp\/v2\/comments?post=23873"}],"version-history":[{"count":22,"href":"https:\/\/oab.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/23873\/revisions"}],"predecessor-version":[{"id":24119,"href":"https:\/\/oab.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/23873\/revisions\/24119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oab.estrategia.com\/portal\/wp-json\/wp\/v2\/media\/24116"}],"wp:attachment":[{"href":"https:\/\/oab.estrategia.com\/portal\/wp-json\/wp\/v2\/media?parent=23873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oab.estrategia.com\/portal\/wp-json\/wp\/v2\/categories?post=23873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oab.estrategia.com\/portal\/wp-json\/wp\/v2\/tags?post=23873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}